{"id":11433,"date":"2021-02-18T16:02:43","date_gmt":"2021-02-18T15:02:43","guid":{"rendered":"http:\/\/veevcom.com\/?p=11433"},"modified":"2021-04-09T15:23:07","modified_gmt":"2021-04-09T13:23:07","slug":"pao-barreto-presente-spiralis","status":"publish","type":"post","link":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/","title":{"rendered":"Pao Barreto presenta \u00abSpiralis\u00bb"},"content":{"rendered":"<p><\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><strong>Dise\u00f1adora de modas, cantante, autora y compositora, la artista colombiana irradia como una espiral incandescente.<\/strong><\/p>\n<p>La historia comienza el 21 de diciembre del 2012, d\u00eda simb\u00f3lico de un nuevo ciclo para la humanidad. Seg\u00fan el calendario Maya, en este d\u00eda se alineaban la tierra y el sol con el sol del centro de la galaxia. La concepci\u00f3n c\u00edclica del tiempo, que la cosmogon\u00eda maya entend\u00eda, marcaba entonces el final de un ciclo c\u00f3smico y uno nuevo al mismo tiempo. Fu\u00e9 en ese momento que la joven Pao, dise\u00f1adora en Bogot\u00e1, llega a Francia. Ella decide partir de su tierra natal para consagrarse plenamente a eso que la motiva profundamente y la hace vibrar desde ni\u00f1a: la m\u00fasica.<\/p>\n<p>Es en Par\u00eds, que ella escoge poner sus maletas para continuar sus estudios musicales, que hab\u00eda provisionalmente dejado de lado. Durante tres a\u00f1os, ella se forma a las percusiones tradicionales en el <strong>CRR Aubervilliers-La Courneuve<\/strong> con su maestro Paul Mindy, y estudia su pregrado de <strong>Etnomusicologia en la Universidad de Paris 8<\/strong>. Paralelamente, su carrera de cantante profesional va nutriendose al lado de grupos de m\u00fasicas latinas de diferentes estilos : m\u00fasicas cubanas con <strong>La Cubanerie<\/strong>, luego <strong>Who\u2019s the Cuban<\/strong>; cumbia de orquesta con <strong>Cumbia Ya!<\/strong> y los r\u00edtmos tradicionales de la costa caribe colombiana con <strong>Cumbia y Card\u00f3n<\/strong>. Pao colabora, de la misma manera, con el grupo <strong>The Bongo Hop<\/strong> con quien ella graba la canci\u00f3n Nos coge la tarde.<\/p>\n<p>Verdadero hurac\u00e1n incandescente, Pao irradia sobre el escenario, y propaga a su alrederor una fuerza de vida poderosa. A medida que van pasando los conciertos, el p\u00fablico va siendo conquistado por su ener\u00eda y su voz plena y calurosa.<\/p>\n<p>Despu\u00e9s de seis a\u00f1os intensos, llenando los escenarios parisinos, franceses e internacionales, la aventura toma un nuevo giro en marzo del 2020 entre Par\u00eds (El Speaker et Nicolas Vair) y Bogot\u00e1 (Groove Studios avec Nicol\u00e1s Cajamarca, Jorge Corredor y Harbey Mar\u00edn : Latin Grammy 2018). Pao graba su primer Album Spiralis como solista, del cu\u00e1l ella es autora-compositora y productora.<\/p>\n<p>Spiralis, la espiral, simbolo de un renovamiento perpetuo de la energ\u00eda vital que circula al infinito. Un s\u00edmbolo que la acompa\u00f1a desde hace mucho tiempo: mucho antes que llegara a Francia, Pao explor\u00f3 durante un largo tiempo, su mundo interior gracias al Yaj\u00e9, bebida sagrada medicinal de los pueblos precolombinos del Putumayo. En ceremonias nocturas dirigidas por los taitas (chamanes), la planta le revelaba invariablemente esta geometr\u00eda sagrada.<\/p>\n<p><strong>DISCOGRAF\u00cdA<\/strong><\/p>\n<p>Con <strong>Spiralis<\/strong>, Pao nos comparte dos aspectos de su universo : por una lado, uno vivo, caluroso y repleto de alegria : y por otro lado, uno m\u00edstico e instrospectivo. Sus composiciones nacen en una multitud de estilos : los r\u00edtmos festivos caribe\u00f1os colombianos (porro, champeta, cumbia) que dialogan con sonidos electr\u00f3nicos y el\u00e9ctricos bien reverberados, a los que se mezclan unas pizcas de soul, funk y reggae. Sus textos en espa\u00f1ol y en franc\u00e9s, celebran sus temas predilectos y amados : la conexi\u00f3n a la naturaleza, el r\u00edtmo c\u00edclico de todo y la capacidad de cada persona a trasformarse y crear su realidad.<\/p>\n<p>A cada lado del Atl\u00e1ntico, la llegada de <strong>Spiralis<\/strong> se prepara: el alb\u00fam sale a principios del 2021. Tienen una cita para continuar a escibir la historia junto a Pao Barreto. Pueden escoger entre descubrir el album con los ojos cerrados y una escucha meditativa o de saborear su alegr\u00eda contagiosa, entrando al baile y al transe&#8230; En todos los casos, estaremos envueltos por una espiral trascendental.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1adora de modas, cantante, autora y compositora, la artista colombiana irradia como una espiral incandescente. La historia comienza el 21 de diciembre del 2012, d\u00eda simb\u00f3lico de un nuevo ciclo para la humanidad. Seg\u00fan el calendario Maya, en este d\u00eda se alineaban la tierra y el sol con el sol del centro de la galaxia. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pao Barreto presenta &quot;Spiralis&quot; - VeevCom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pao Barreto presenta &quot;Spiralis&quot; - VeevCom\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1adora de modas, cantante, autora y compositora, la artista colombiana irradia como una espiral incandescente. La historia comienza el 21 de diciembre del 2012, d\u00eda simb\u00f3lico de un nuevo ciclo para la humanidad. Seg\u00fan el calendario Maya, en este d\u00eda se alineaban la tierra y el sol con el sol del centro de la galaxia. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/\" \/>\n<meta property=\"og:site_name\" content=\"VeevCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-18T15:02:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T13:23:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD-1024x930.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"severine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"severine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/\"},\"author\":{\"name\":\"severine\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/#\\\/schema\\\/person\\\/754f1f5a030d278766b52cf0e0c62e8b\"},\"headline\":\"Pao Barreto presenta \u00abSpiralis\u00bb\",\"datePublished\":\"2021-02-18T15:02:43+00:00\",\"dateModified\":\"2021-04-09T13:23:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/\"},\"wordCount\":1502,\"image\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veevcom.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/\",\"url\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/\",\"name\":\"Pao Barreto presenta \\\"Spiralis\\\" - VeevCom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veevcom.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png\",\"datePublished\":\"2021-02-18T15:02:43+00:00\",\"dateModified\":\"2021-04-09T13:23:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/#\\\/schema\\\/person\\\/754f1f5a030d278766b52cf0e0c62e8b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veevcom.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png\",\"contentUrl\":\"https:\\\/\\\/veevcom.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png\",\"width\":1121,\"height\":1018},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/pao-barreto-presente-spiralis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/veevcom.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pao Barreto presenta \u00abSpiralis\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/veevcom.com\\\/es\\\/\",\"name\":\"VeevCom\",\"description\":\"Public Relations and Communication in the Music Industry\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veevcom.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veevcom.com\\\/#\\\/schema\\\/person\\\/754f1f5a030d278766b52cf0e0c62e8b\",\"name\":\"severine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g\",\"caption\":\"severine\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pao Barreto presenta \"Spiralis\" - VeevCom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/","og_locale":"es_ES","og_type":"article","og_title":"Pao Barreto presenta \"Spiralis\" - VeevCom","og_description":"Dise\u00f1adora de modas, cantante, autora y compositora, la artista colombiana irradia como una espiral incandescente. La historia comienza el 21 de diciembre del 2012, d\u00eda simb\u00f3lico de un nuevo ciclo para la humanidad. Seg\u00fan el calendario Maya, en este d\u00eda se alineaban la tierra y el sol con el sol del centro de la galaxia. [&hellip;]","og_url":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/","og_site_name":"VeevCom","article_published_time":"2021-02-18T15:02:43+00:00","article_modified_time":"2021-04-09T13:23:07+00:00","og_image":[{"width":1024,"height":930,"url":"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD-1024x930.png","type":"image\/png"}],"author":"severine","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"severine","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#article","isPartOf":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/"},"author":{"name":"severine","@id":"https:\/\/veevcom.com\/#\/schema\/person\/754f1f5a030d278766b52cf0e0c62e8b"},"headline":"Pao Barreto presenta \u00abSpiralis\u00bb","datePublished":"2021-02-18T15:02:43+00:00","dateModified":"2021-04-09T13:23:07+00:00","mainEntityOfPage":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/"},"wordCount":1502,"image":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#primaryimage"},"thumbnailUrl":"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png","articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/","url":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/","name":"Pao Barreto presenta \"Spiralis\" - VeevCom","isPartOf":{"@id":"https:\/\/veevcom.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#primaryimage"},"image":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#primaryimage"},"thumbnailUrl":"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png","datePublished":"2021-02-18T15:02:43+00:00","dateModified":"2021-04-09T13:23:07+00:00","author":{"@id":"https:\/\/veevcom.com\/#\/schema\/person\/754f1f5a030d278766b52cf0e0c62e8b"},"breadcrumb":{"@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#primaryimage","url":"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png","contentUrl":"https:\/\/veevcom.com\/wp-content\/uploads\/2021\/02\/FRONT\u00a9NUINO-VISUAL-LEAH-COLD.png","width":1121,"height":1018},{"@type":"BreadcrumbList","@id":"https:\/\/veevcom.com\/es\/pao-barreto-presente-spiralis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/veevcom.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pao Barreto presenta \u00abSpiralis\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/veevcom.com\/es\/#website","url":"https:\/\/veevcom.com\/es\/","name":"VeevCom","description":"Public Relations and Communication in the Music Industry","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veevcom.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/veevcom.com\/#\/schema\/person\/754f1f5a030d278766b52cf0e0c62e8b","name":"severine","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba307ed472519f403589981b25bf62b4089c1f82b837eaae855dd05633adf22c?s=96&d=mm&r=g","caption":"severine"}}]}},"_links":{"self":[{"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/posts\/11433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/comments?post=11433"}],"version-history":[{"count":6,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/posts\/11433\/revisions"}],"predecessor-version":[{"id":11528,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/posts\/11433\/revisions\/11528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/media\/11435"}],"wp:attachment":[{"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/media?parent=11433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/categories?post=11433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veevcom.com\/es\/wp-json\/wp\/v2\/tags?post=11433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}